{"id":112,"count":6,"description":"","link":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/","name":"Gebrauchte Maschinen","slug":"gebrauchte-maschinen","taxonomy":"machine_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gebrauchte Maschinen | Groupe Thibaut<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebrauchte Maschinen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Thibaut\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thibaut.fr\/wp-content\/uploads\/2025\/12\/Logo-THIBAUT-CMJN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/machine-category\\\/gebrauchte-maschinen\\\/\",\"url\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/machine-category\\\/gebrauchte-maschinen\\\/\",\"name\":\"Gebrauchte Maschinen | Groupe Thibaut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/machine-category\\\/gebrauchte-maschinen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/machine-category\\\/gebrauchte-maschinen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Machines\",\"item\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gebrauchte Maschinen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/\",\"name\":\"Groupe Thibaut\",\"description\":\"L&#039;excellence au service de la pierre depuis 1959\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#organization\"},\"alternateName\":\"Thibaut\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#organization\",\"name\":\"Groupe Thibaut\",\"alternateName\":\"Thibaut\",\"url\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thibaut.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo-THIBAUT-CMJN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thibaut.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo-THIBAUT-CMJN.jpg\",\"width\":1181,\"height\":286,\"caption\":\"Groupe Thibaut\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thibaut.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thibautgroupe\",\"https:\\\/\\\/www.instagram.com\\\/thibautgroupe\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4yln9Xigw8FvApMJU5c_HA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/thibaut-sa\\\/\"],\"description\":\"Manufacturing company\",\"email\":\"marketing@thibaut.fr\",\"telephone\":\"+33(0)2 31 66 68 00\",\"legalName\":\"Thibaut\",\"foundingDate\":\"1959-01-01\",\"vatID\":\"FR00377782792\",\"taxID\":\"37778279200016\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gebrauchte Maschinen | Groupe Thibaut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/","og_locale":"de_DE","og_type":"article","og_title":"Gebrauchte Maschinen","og_url":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/","og_site_name":"Groupe Thibaut","og_image":[{"width":1181,"height":286,"url":"https:\/\/www.thibaut.fr\/wp-content\/uploads\/2025\/12\/Logo-THIBAUT-CMJN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/","url":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/","name":"Gebrauchte Maschinen | Groupe Thibaut","isPartOf":{"@id":"https:\/\/www.thibaut.fr\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thibaut.fr\/de\/machine-category\/gebrauchte-maschinen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thibaut.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Machines","item":"https:\/\/www.thibaut.fr\/de\/machine\/"},{"@type":"ListItem","position":3,"name":"Gebrauchte Maschinen"}]},{"@type":"WebSite","@id":"https:\/\/www.thibaut.fr\/de\/#website","url":"https:\/\/www.thibaut.fr\/de\/","name":"Groupe Thibaut","description":"L&#039;excellence au service de la pierre depuis 1959","publisher":{"@id":"https:\/\/www.thibaut.fr\/de\/#organization"},"alternateName":"Thibaut","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thibaut.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.thibaut.fr\/de\/#organization","name":"Groupe Thibaut","alternateName":"Thibaut","url":"https:\/\/www.thibaut.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thibaut.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.thibaut.fr\/wp-content\/uploads\/2025\/12\/Logo-THIBAUT-CMJN.jpg","contentUrl":"https:\/\/www.thibaut.fr\/wp-content\/uploads\/2025\/12\/Logo-THIBAUT-CMJN.jpg","width":1181,"height":286,"caption":"Groupe Thibaut"},"image":{"@id":"https:\/\/www.thibaut.fr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thibautgroupe","https:\/\/www.instagram.com\/thibautgroupe\/","https:\/\/www.youtube.com\/channel\/UC4yln9Xigw8FvApMJU5c_HA","https:\/\/www.linkedin.com\/company\/thibaut-sa\/"],"description":"Manufacturing company","email":"marketing@thibaut.fr","telephone":"+33(0)2 31 66 68 00","legalName":"Thibaut","foundingDate":"1959-01-01","vatID":"FR00377782792","taxID":"37778279200016","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.thibaut.fr\/de\/wp-json\/wp\/v2\/machine_category\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thibaut.fr\/de\/wp-json\/wp\/v2\/machine_category"}],"about":[{"href":"https:\/\/www.thibaut.fr\/de\/wp-json\/wp\/v2\/taxonomies\/machine_category"}],"wp:post_type":[{"href":"https:\/\/www.thibaut.fr\/de\/wp-json\/wp\/v2\/machine?machine_category=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}